{"id":2426,"date":"2021-10-23T09:24:18","date_gmt":"2021-10-23T09:24:18","guid":{"rendered":"https:\/\/tjeerdgeerts.com\/?page_id=224"},"modified":"2021-11-15T15:21:32","modified_gmt":"2021-11-15T14:21:32","slug":"boek-een-afspraak","status":"publish","type":"page","link":"https:\/\/tjeerdgeerts.com\/nl\/boek-een-afspraak\/","title":{"rendered":"Boek een gratis consult"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2426\" class=\"elementor elementor-2426 elementor-224\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e31c875 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e31c875\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16d437d5\" data-id=\"16d437d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64cf061 elementor-widget elementor-widget-text-editor\" data-id=\"64cf061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ik raad u aan om een vrijblijvend en kosteloos consult te boeken om u te laten informeren over de mogelijkheden voor u, om uw probleem of conditie met hypnotherapie op te lossen. Er zijn iedere werkdag twee mogelijkheden in de ochtend en \u00e9\u00e9n op zaterdagochtend. U kunt mij ook bellen op +34 688 883 183 of mij vragen stellen via de WhatsApp op hetzelfde nummer of gebruik te maken van de WhatsApp knop hier links onderaan op de site.\u00a0 <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ffc3926 elementor-widget elementor-widget-shortcode\" data-id=\"2ffc3926\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"booked-calendar-shortcode-wrap\"><div class=\"booked-calendar-wrap large\"><div class=\"booked-calendar\" data-calendar-id=\"8\" data-calendar-date=\"2026-05-01\">\n\t\t<div class=\"bc-head\">\n\n\t\t\t\n\t\t\t<div class=\"bc-row top\">\n\t\t\t\t<div class=\"bc-col\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"calendarSavingState\">\n\t\t\t\t\t\t<i class=\"fa-solid fa-circle-notch fa-spin\"><\/i>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"monthName\">\n\t\t\t\t\t\tmei 2026\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<a href=\"#\" data-goto=\"2026-06-01\" class=\"page-right\"><i class=\"fa-solid fa-arrow-right\"><\/i><\/a>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"bc-row days\">\n\t\t\t\t\t\t\t\t<div class=\"bc-col\">ma<\/div>\n\t\t\t\t<div class=\"bc-col\">di<\/div>\n\t\t\t\t<div class=\"bc-col\">wo<\/div>\n\t\t\t\t<div class=\"bc-col\">do<\/div>\n\t\t\t\t<div class=\"bc-col\">vr<\/div>\n\t\t\t\t<div class=\"bc-col\">za<\/div>\t\t\t\t<div class=\"bc-col\">zo<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"bc-body\"><div class=\"bc-row week\"><div data-date=\"2026-04-27\" class=\"bc-col prev-month prev-date\"><span class=\"date\"><span class=\"number\">27<\/span><\/span><\/div><div data-date=\"2026-04-28\" class=\"bc-col prev-month prev-date\"><span class=\"date\"><span class=\"number\">28<\/span><\/span><\/div><div data-date=\"2026-04-29\" class=\"bc-col prev-month prev-date\"><span class=\"date\"><span class=\"number\">29<\/span><\/span><\/div><div data-date=\"2026-04-30\" class=\"bc-col prev-month prev-date\"><span class=\"date\"><span class=\"number\">30<\/span><\/span><\/div><div data-date=\"2026-05-1\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">1<\/span><\/span><\/div><div data-date=\"2026-05-2\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">2<\/span><\/span><\/div><div data-date=\"2026-05-3\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">3<\/span><\/span><\/div><\/div><div class=\"bc-row week\"><div data-date=\"2026-05-4\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">4<\/span><\/span><\/div><div data-date=\"2026-05-5\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">5<\/span><\/span><\/div><div data-date=\"2026-05-6\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">6<\/span><\/span><\/div><div data-date=\"2026-05-7\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">7<\/span><\/span><\/div><div data-date=\"2026-05-8\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">8<\/span><\/span><\/div><div data-date=\"2026-05-9\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">9<\/span><\/span><\/div><div data-date=\"2026-05-10\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">10<\/span><\/span><\/div><\/div><div class=\"bc-row week\"><div data-date=\"2026-05-11\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">11<\/span><\/span><\/div><div data-date=\"2026-05-12\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">12<\/span><\/span><\/div><div data-date=\"2026-05-13\" class=\"bc-col today prev-date\"><span class=\"date\"><span class=\"number\">13<\/span><\/span><\/div><div data-date=\"2026-05-14\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">14<\/span><\/span><\/div><div data-date=\"2026-05-15\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">15<\/span><\/span><\/div><div data-date=\"2026-05-16\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"1 Beschikbaar\"><span class=\"number\">16<\/span><\/span><\/div><div data-date=\"2026-05-17\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">17<\/span><\/span><\/div><\/div><div class=\"bc-row week\"><div data-date=\"2026-05-18\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">18<\/span><\/span><\/div><div data-date=\"2026-05-19\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">19<\/span><\/span><\/div><div data-date=\"2026-05-20\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">20<\/span><\/span><\/div><div data-date=\"2026-05-21\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">21<\/span><\/span><\/div><div data-date=\"2026-05-22\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">22<\/span><\/span><\/div><div data-date=\"2026-05-23\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"1 Beschikbaar\"><span class=\"number\">23<\/span><\/span><\/div><div data-date=\"2026-05-24\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">24<\/span><\/span><\/div><\/div><div class=\"bc-row week\"><div data-date=\"2026-05-25\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">25<\/span><\/span><\/div><div data-date=\"2026-05-26\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">26<\/span><\/span><\/div><div data-date=\"2026-05-27\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">27<\/span><\/span><\/div><div data-date=\"2026-05-28\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">28<\/span><\/span><\/div><div data-date=\"2026-05-29\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"2 Beschikbaar\"><span class=\"number\">29<\/span><\/span><\/div><div data-date=\"2026-05-30\" class=\"bc-col \"><span class=\"date tooltipster\" title=\"1 Beschikbaar\"><span class=\"number\">30<\/span><\/span><\/div><div data-date=\"2026-05-31\" class=\"bc-col prev-date\"><span class=\"date\"><span class=\"number\">31<\/span><\/span><\/div><\/div>\t\t<\/div>\n\t<\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ik raad u aan om een vrijblijvend en kosteloos consult te boeken om u te laten informeren over de mogelijkheden voor u, om uw probleem of conditie met hypnotherapie op te lossen. Er zijn iedere werkdag twee mogelijkheden in de &hellip; <a href=\"https:\/\/tjeerdgeerts.com\/nl\/boek-een-afspraak\/\">Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-2426","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/pages\/2426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/comments?post=2426"}],"version-history":[{"count":12,"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/pages\/2426\/revisions"}],"predecessor-version":[{"id":2958,"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/pages\/2426\/revisions\/2958"}],"wp:attachment":[{"href":"https:\/\/tjeerdgeerts.com\/nl\/wp-json\/wp\/v2\/media?parent=2426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}